{"id":1050,"date":"2015-03-05T18:57:00","date_gmt":"2015-03-05T17:57:00","guid":{"rendered":"https:\/\/psy.brussels\/?p=1050"},"modified":"2023-01-21T18:57:46","modified_gmt":"2023-01-21T17:57:46","slug":"aspects-psychologiques-de-la-vie-dans-un-autre-pays","status":"publish","type":"post","link":"https:\/\/www.psychologist.brussels\/fr\/2015\/aspects-psychologiques-de-la-vie-dans-un-autre-pays\/","title":{"rendered":"Aspects psychologiques de la vie dans un autre pays"},"content":{"rendered":"\n<p><strong>Vous vivez dans un nouveau pays depuis quelques mois,<\/strong> et vous avez d\u00e9ball\u00e9 vos valises et cartons. Vous avez lu toutes sortes d&rsquo;informations sur le logement, les transports, le travail, les \u00e9coles, la sant\u00e9, les imp\u00f4ts, la paperasse. Petit \u00e0 petit les choses se mettent en place et vous faites de votre mieux pour vous installer au plus vite, pour vous sentir chez vous et \u00e0 l&rsquo;aise.<\/p>\n\n\n\n<p><strong>Et comment vous sentez-vous ? Est-ce que vous y avez penser?<\/strong> D\u00e9m\u00e9nager est consid\u00e9r\u00e9 comme une exp\u00e9rience tr\u00e8s stressante, tout comme changer d&#8217;emploi, chercher un emploi, changer de pays, etc. Dans votre cas, tout en un. Vous vivez beaucoup de changements autour de vous avec plus d&rsquo;exigences que d&rsquo;habitude et ce nouvel environnement demande de l&rsquo;adaptation.<\/p>\n\n\n\n<p>Dans certains cas, les expatri\u00e9s recherchent une <a href=\"https:\/\/psy.brussels\/fr\/2015\/psychotherapie-quand-y-aller\/\" title=\"Psychoth\u00e9rapie, quand y aller?\">th\u00e9rapie<\/a> motiv\u00e9s en partie par la frustration d&rsquo;\u00eatre isol\u00e9s. Quels que soient les probl\u00e8mes qui conduisent \u00e0 d\u00e9buter une th\u00e9rapie, les causes les plus fr\u00e9quentes sont que les personnes n&rsquo;ont pas d&rsquo;amis (ou moins proches) ou de famille proche \u00e0 qui confier leurs difficult\u00e9s actuelles. Pour n&rsquo;importe qui, la pression qui s&rsquo;accumule du fait de ne pas pouvoir partager les luttes peut \u00eatre exasp\u00e9rante. Cela semble encore s&rsquo;intensifier pour les personnes vivant \u00e0 l&rsquo;\u00e9tranger.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Syndrome du migrant (syndrome d\u2019Ulysse)<\/h2>\n\n\n\n<p>Bien que la plupart des gens parviennent \u00e0 faire face aux aspects n\u00e9gatifs de la migration gr\u00e2ce \u00e0 l\u2019existence d\u2019autres aspects positifs,\u00a0<mark><mark style=\"background-color:#ffffff\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>la migration est un facteur de risque pour la sant\u00e9 mentale en raison du stress migratoire ou du deuil<\/strong>, appel\u00e9 syndrome de l\u2019immigrant ou syndrome d\u2019Ulysse.<\/mark><\/mark><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sources de stress<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La solitude caus\u00e9e par la s\u00e9paration des \u00eatres chers.<\/li>\n\n\n\n<li>Un sentiment de d\u00e9sespoir et d\u2019\u00e9chec \u00e0 cause de peu d\u2019opportunit\u00e9s de progresser avec un projet \u00e0 l\u2019\u00e9tranger.<\/li>\n\n\n\n<li>Absence d\u2019un r\u00e9seau de soutien social.<\/li>\n\n\n\n<li>Lutter contre les probl\u00e8mes \u00e9conomiques tels que le paiement du logement, de la nourriture.<\/li>\n\n\n\n<li>Peur ou d\u00e9sorientation.<\/li>\n\n\n\n<li>Temporalit\u00e9 d\u2019une situation.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Les \u00e9tapes du deuil<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9ni :<\/strong>&nbsp;la r\u00e9alit\u00e9 du changement n\u2019est pas accept\u00e9e.<\/li>\n\n\n\n<li><strong>R\u00e9sistance :<\/strong>&nbsp;face aux difficult\u00e9s et aux d\u00e9fis, se plaint de l\u2019effort n\u00e9cessaire pour s\u2019adapter \u00e0 la nouvelle situation.<\/li>\n\n\n\n<li><strong>Acceptation :<\/strong>&nbsp;s\u2019installe compl\u00e8tement dans la nouvelle situation.<\/li>\n\n\n\n<li><strong>Restitution :<\/strong>&nbsp;accepter les aspects positifs et n\u00e9gatifs du pays d\u2019origine et du pays d\u2019accueil implique une r\u00e9conciliation affective.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">D\u00e9fenses psychologiques<\/h3>\n\n\n\n<p>Les gens utilisent une s\u00e9rie de m\u00e9canismes de d\u00e9fense psychologiques ou d\u2019erreurs afin de les aider \u00e0 faire face \u00e0 la nouvelle situation \u00e0 l\u2019\u00e9tranger. Ils ne sont pas en eux-m\u00eames n\u00e9gatifs mais&nbsp;<strong>lorsqu\u2019ils sont nombreux, ils d\u00e9forment radicalement la vision que nous avons de la r\u00e9alit\u00e9 et nous emp\u00eachent de nous adapter et de nous pr\u00e9parer au deuil migratoire.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019abstraction s\u00e9lective consiste \u00e0 se concentrer sur un d\u00e9tail hors de son contexte.<\/li>\n\n\n\n<li>Inf\u00e9rence arbitraire, g\u00e9n\u00e9ralisation excessive lorsqu\u2019une conclusion ou une r\u00e8gle est tir\u00e9e d\u2019un ou plusieurs faits isol\u00e9s.<\/li>\n\n\n\n<li>Maximisation et minimisation, distorsion modifiant l\u2019ampleur des \u00e9v\u00e9nements.<\/li>\n\n\n\n<li>Personnalisation, attribution injustifi\u00e9e de ph\u00e9nom\u00e8nes externes.<\/li>\n\n\n\n<li>La pens\u00e9e absolutiste ou dichotomique classe les exp\u00e9riences en \u00ab tout ou rien \u00bb, en cat\u00e9gories extr\u00eames.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Vous vivez dans un nouveau pays depuis quelques mois, et vous avez d\u00e9ball\u00e9 vos valises et cartons. Vous avez lu toutes sortes d&rsquo;informations sur le logement,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1050","post","type-post","status-publish","format-standard","hentry","category-general"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/posts\/1050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/comments?post=1050"}],"version-history":[{"count":1,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/posts\/1050\/revisions"}],"predecessor-version":[{"id":1051,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/posts\/1050\/revisions\/1051"}],"wp:attachment":[{"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/media?parent=1050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/categories?post=1050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologist.brussels\/fr\/wp-json\/wp\/v2\/tags?post=1050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}